{"id":7523,"date":"2020-01-23T11:44:05","date_gmt":"2020-01-23T09:44:05","guid":{"rendered":"https:\/\/energiakeskus.ee\/?post_type=tegevused_cpt&#038;p=7523"},"modified":"2023-12-15T16:22:45","modified_gmt":"2023-12-15T14:22:45","slug":"solntse-nasha-zhivaya-zvezda","status":"publish","type":"tegevused_cpt","link":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/","title":{"rendered":"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430"},"content":{"rendered":"","protected":false},"featured_media":7504,"parent":0,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"is_birthday_cat":[],"class_list":["post-7523","tegevused_cpt","type-tegevused_cpt","status-publish","has-post-thumbnail","hentry","tegevused_cat-planetaariumi-film-ru"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430 - \u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430 - \u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Energiakeskus\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T14:22:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energiakeskus.ee\/static\/2020\/01\/Sun-our-living-star_veeb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1779\" \/>\n\t<meta property=\"og:image:height\" content=\"951\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/\",\"url\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/\",\"name\":\"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430 - \u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.energiakeskus.ee\\\/static\\\/2020\\\/01\\\/Sun-our-living-star_veeb.jpg\",\"datePublished\":\"2020-01-23T09:44:05+00:00\",\"dateModified\":\"2023-12-15T14:22:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.energiakeskus.ee\\\/static\\\/2020\\\/01\\\/Sun-our-living-star_veeb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.energiakeskus.ee\\\/static\\\/2020\\\/01\\\/Sun-our-living-star_veeb.jpg\",\"width\":1779,\"height\":951,\"caption\":\"Poster for The Sun, Our Living Star\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/tegevused-post\\\/solntse-nasha-zhivaya-zvezda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/\",\"name\":\"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb\",\"description\":\"O\u0442\u043a\u0440\u044b\u0432\u0430\u0439, \u0438\u0433\u0440\u0430\u0439, \u0443\u0447\u0438\u0441\u044c!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/#organization\",\"name\":\"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb\",\"url\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.energiakeskus.ee\\\/static\\\/2022\\\/05\\\/EAK_web_covid-1.png\",\"contentUrl\":\"https:\\\/\\\/www.energiakeskus.ee\\\/static\\\/2022\\\/05\\\/EAK_web_covid-1.png\",\"width\":1500,\"height\":750,\"caption\":\"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.energiakeskus.ee\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Energiakeskus\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430 - \u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430 - \u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb","og_url":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/","og_site_name":"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb","article_publisher":"https:\/\/www.facebook.com\/Energiakeskus","article_modified_time":"2023-12-15T14:22:45+00:00","og_image":[{"width":1779,"height":951,"url":"https:\/\/energiakeskus.ee\/static\/2020\/01\/Sun-our-living-star_veeb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/","url":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/","name":"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430 - \u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb","isPartOf":{"@id":"https:\/\/www.energiakeskus.ee\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/#primaryimage"},"image":{"@id":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.energiakeskus.ee\/static\/2020\/01\/Sun-our-living-star_veeb.jpg","datePublished":"2020-01-23T09:44:05+00:00","dateModified":"2023-12-15T14:22:45+00:00","breadcrumb":{"@id":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/#primaryimage","url":"https:\/\/www.energiakeskus.ee\/static\/2020\/01\/Sun-our-living-star_veeb.jpg","contentUrl":"https:\/\/www.energiakeskus.ee\/static\/2020\/01\/Sun-our-living-star_veeb.jpg","width":1779,"height":951,"caption":"Poster for The Sun, Our Living Star"},{"@type":"BreadcrumbList","@id":"https:\/\/www.energiakeskus.ee\/ru\/tegevused-post\/solntse-nasha-zhivaya-zvezda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.energiakeskus.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"\u0421\u043e\u043b\u043d\u0446\u0435 \u2013 \u043d\u0430\u0448\u0430 \u0436\u0438\u0432\u0430\u044f \u0437\u0432\u0435\u0437\u0434\u0430"}]},{"@type":"WebSite","@id":"https:\/\/www.energiakeskus.ee\/ru\/#website","url":"https:\/\/www.energiakeskus.ee\/ru\/","name":"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb","description":"O\u0442\u043a\u0440\u044b\u0432\u0430\u0439, \u0438\u0433\u0440\u0430\u0439, \u0443\u0447\u0438\u0441\u044c!","publisher":{"@id":"https:\/\/www.energiakeskus.ee\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.energiakeskus.ee\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/www.energiakeskus.ee\/ru\/#organization","name":"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb","url":"https:\/\/www.energiakeskus.ee\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.energiakeskus.ee\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/www.energiakeskus.ee\/static\/2022\/05\/EAK_web_covid-1.png","contentUrl":"https:\/\/www.energiakeskus.ee\/static\/2022\/05\/EAK_web_covid-1.png","width":1500,"height":750,"caption":"\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0446\u0435\u043d\u0442\u0440 \u00ab\u042d\u043d\u0435\u0440\u0433\u0438\u044f\u00bb"},"image":{"@id":"https:\/\/www.energiakeskus.ee\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Energiakeskus"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.energiakeskus.ee\/ru\/wp-json\/wp\/v2\/tegevused_cpt\/7523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.energiakeskus.ee\/ru\/wp-json\/wp\/v2\/tegevused_cpt"}],"about":[{"href":"https:\/\/www.energiakeskus.ee\/ru\/wp-json\/wp\/v2\/types\/tegevused_cpt"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.energiakeskus.ee\/ru\/wp-json\/wp\/v2\/media\/7504"}],"wp:attachment":[{"href":"https:\/\/www.energiakeskus.ee\/ru\/wp-json\/wp\/v2\/media?parent=7523"}],"wp:term":[{"taxonomy":"is_birthday_cat","embeddable":true,"href":"https:\/\/www.energiakeskus.ee\/ru\/wp-json\/wp\/v2\/is_birthday_cat?post=7523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}